{"id":167,"count":3,"description":"","link":"https:\/\/elaramedical.com\/it\/servizi\/chirurgia-estetica\/interventi-al-seno\/","name":"Interventi al seno","slug":"interventi-al-seno","taxonomy":"category","parent":127,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/elaramedical.com\/it\/wp-json\/wp\/v2\/categories\/167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elaramedical.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/elaramedical.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/elaramedical.com\/it\/wp-json\/wp\/v2\/categories\/127"}],"wp:post_type":[{"href":"https:\/\/elaramedical.com\/it\/wp-json\/wp\/v2\/posts?categories=167"},{"href":"https:\/\/elaramedical.com\/it\/wp-json\/wp\/v2\/blog-posts?categories=167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}